{"id":101076,"date":"2026-03-30T11:57:51","date_gmt":"2026-03-30T09:57:51","guid":{"rendered":"https:\/\/cultureelpersbureau.nl\/?p=101076"},"modified":"2026-03-30T11:57:56","modified_gmt":"2026-03-30T09:57:56","slug":"wat-bestuur-en-toezicht-moeten-weten-over-softwaresoevereiniteit","status":"publish","type":"post","link":"https:\/\/cultureelpersbureau.nl\/fr\/2026\/03\/wat-bestuur-en-toezicht-moeten-weten-over-softwaresoevereiniteit\/","title":{"rendered":"Ce que la gouvernance et la supervision doivent savoir sur la souverainet\u00e9 logicielle"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Dans un article pr\u00e9c\u00e9dent, j'ai parl\u00e9 du mythe de la voie num\u00e9rique : l'id\u00e9e persistante que les institutions culturelles, avec suffisamment de volont\u00e9 politique ou morale, peuvent changer de cap num\u00e9rique relativement facilement. Moins de d\u00e9pendance \u00e0 l'\u00e9gard de la technologie am\u00e9ricaine, plus d'utilisation des alternatives europ\u00e9ennes, plus de contr\u00f4le sur les donn\u00e9es et l'infrastructure. Cela semble simple. Presque rassurant, mais un examen plus approfondi r\u00e9v\u00e8le autre chose : l'infrastructure num\u00e9rique n'est pas une voie que l'on d\u00e9place, mais un empilement de logiciels, de nuages, de donn\u00e9es, d'identit\u00e9, de s\u00e9curit\u00e9, d'archivage et maintenant d'IA. C'est pr\u00e9cis\u00e9ment cette interconnexion qui rend le sujet pertinent d'un point de vue administratif.\u00a0 \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La question de la souverainet\u00e9 logicielle n'est donc plus un hobby des d\u00e9partements informatiques. Elle touche au c\u0153ur de la gouvernance et de la supervision. En effet, d\u00e8s qu'une institution ne dispose plus d'une vue d'ensemble claire des syst\u00e8mes num\u00e9riques dont elle d\u00e9pend, sa capacit\u00e9 \u00e0 prendre des d\u00e9cisions de mani\u00e8re ind\u00e9pendante diminue \u00e9galement. Ce sont alors les fournisseurs, les conditions contractuelles, l'habitude et la pression du temps qui prennent les d\u00e9cisions.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ce n'est pas le drapeau sur la fa\u00e7ade, mais le degr\u00e9 d'orientation.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Dans le d\u00e9bat, la souverainet\u00e9 logicielle est souvent r\u00e9duite \u00e0 l'origine. L'Europ\u00e9en serait plus s\u00fbr ou plus autonome, l'Am\u00e9ricain plus risqu\u00e9. Cette intuition est compr\u00e9hensible, surtout \u00e0 l'heure des tensions g\u00e9opolitiques et de la suspicion croissante \u00e0 l'\u00e9gard des Big Tech. Mais pour la gouvernance et la supervision, elle est trop simpliste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0La question pertinente n'est pas seulement de savoir d'o\u00f9 vient un fournisseur, mais aussi de conna\u00eetre le degr\u00e9 de contr\u00f4le que l'institution elle-m\u00eame conserve. Peut-elle d\u00e9placer ses donn\u00e9es ? Comprend-elle quels r\u00e9gimes juridiques s'appliquent ? Sait-elle ce qui se passe si les conditions changent, si les prix augmentent ou si l'acc\u00e8s \u00e0 certains services est soumis \u00e0 des pressions ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette distinction est devenue tr\u00e8s visible dans l'affaire concernant la Commission europ\u00e9enne et Microsoft 365. En mars 2024, le Contr\u00f4leur europ\u00e9en de la protection des donn\u00e9es a jug\u00e9 que l'utilisation de Microsoft 365 par la Commission violait les r\u00e8gles applicables en mati\u00e8re de protection de la vie priv\u00e9e \u00e0 plusieurs \u00e9gards, notamment en ce qui concerne les transferts internationaux de donn\u00e9es et les divulgations non autoris\u00e9es. La Commission a ensuite d\u00fb adapter son utilisation et l'a mise en conformit\u00e9 avec les r\u00e8gles en juillet 2025, selon le r\u00e9gulateur. La le\u00e7on est claire : le fait que les donn\u00e9es se trouvent en Europe ou qu'une institution publique travaille avec une grande organisation ne signifie pas automatiquement que la gouvernance est en place. La localisation des donn\u00e9es ne suffit pas \u00e0 assurer la souverainet\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les institutions culturelles, il ne s'agit pas d'une question abstraite de Bruxelles. Elles aussi travaillent avec les donn\u00e9es personnelles des visiteurs, du personnel, des artistes, des donateurs et des partenaires. La gestion et la supervision doivent donc se demander non seulement o\u00f9 se trouvent les donn\u00e9es, mais aussi sous quel r\u00e9gime juridique et contractuel elles circulent r\u00e9ellement.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La vuln\u00e9rabilit\u00e9 se situe au niveau de l'empilage<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, la v\u00e9ritable d\u00e9pendance d\u00e9coule rarement d'un syst\u00e8me unique et l\u00e2che. Elle se situe au niveau de l'empilement. Une institution utilise Microsoft 365 ou Google Workspace pour le courrier et les documents, poss\u00e8de des donn\u00e9es dans un environnement en nuage, g\u00e8re les identit\u00e9s via des syst\u00e8mes li\u00e9s, s'appuie sur des logiciels de s\u00e9curit\u00e9 de fournisseurs sp\u00e9cialis\u00e9s, utilise des plateformes externes pour la collaboration et, entre-temps, laisse les employ\u00e9s exp\u00e9rimenter les outils d'IA. Tous ces \u00e9l\u00e9ments sont imbriqu\u00e9s les uns dans les autres. Par cons\u00e9quent, les logiciels ne sont plus une collection de produits individuels, mais un \u00e9cosyst\u00e8me.\u00a0 \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La panne mondiale de CrowdStrike en juillet 2024 a douloureusement montr\u00e9 ce que cela signifie. L'incident a \u00e9t\u00e9 caus\u00e9 par une mise \u00e0 jour d\u00e9fectueuse du contenu des h\u00f4tes Windows et n'\u00e9tait absolument pas une cyberattaque, selon CrowdStrike. Pourtant, une faille dans un lien de s\u00e9curit\u00e9 dominant a entra\u00een\u00e9 une perturbation mondiale. C'est pr\u00e9cis\u00e9ment l\u00e0 que r\u00e9side la le\u00e7on \u00e0 tirer en mati\u00e8re de gestion. La d\u00e9pendance n'est pas seulement une question de confidentialit\u00e9 ou de g\u00e9opolitique, mais aussi une question de continuit\u00e9. Lorsqu'un fournisseur se trouve au c\u0153ur de la cha\u00eene num\u00e9rique, un probl\u00e8me technique peut se traduire par un temps d'arr\u00eat op\u00e9rationnel \u00e0 la vitesse de l'\u00e9clair.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour un mus\u00e9e, une sc\u00e8ne ou des archives, c'est tr\u00e8s concret. Il ne s'agit pas d'un \u201cincident\u201d abstrait, mais de l'impossibilit\u00e9 d'acc\u00e9der aux documents, de planifier, de communiquer en interne, \u00e9ventuellement de vendre des billets et d'avoir une vision claire des informations qui ont \u00e9t\u00e9 touch\u00e9es. Ce qui commence sur le plan technique finit sur le plan administratif.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Le verrouillage se d\u00e9veloppe souvent sans que personne ne l'ait vraiment d\u00e9cid\u00e9<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00c0 cela s'ajoute une v\u00e9rit\u00e9 d\u00e9sagr\u00e9able. De nombreuses institutions n'ont pas choisi consciemment la d\u00e9pendance maximale. Elles y sont entr\u00e9es progressivement. Elles ont d'abord ajout\u00e9 un environnement de bureau, puis une couche d'informatique d\u00e9mat\u00e9rialis\u00e9e, puis une s\u00e9curit\u00e9 suppl\u00e9mentaire, puis une autre fonctionnalit\u00e9 d'IA parce qu'elle \u00e9tait standard ou parce que les employ\u00e9s l'avaient demand\u00e9e. Le verrouillage est rarement le fruit d'une seule grande d\u00e9cision. Il r\u00e9sulte d'une s\u00e9rie de petits choix compr\u00e9hensibles d'un point de vue pratique qui, ensemble, cr\u00e9ent un seuil de basculement \u00e9lev\u00e9.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Les changements de tarification et de conditionnement de Microsoft pour Microsoft 365, annonc\u00e9s en d\u00e9cembre 2025 et entrant en vigueur le 1er juillet 2026, illustrent cette dynamique. Microsoft y associe de plus en plus explicitement des fonctionnalit\u00e9s suppl\u00e9mentaires d'IA, de s\u00e9curit\u00e9 et de gestion aux suites existantes. En soi, cela a du sens du point de vue du d\u00e9veloppement de produits, mais du point de vue de la gestion, cela signifie \u00e9galement autre chose : plus les fonctions sont r\u00e9unies dans un seul environnement, plus il devient difficile d'\u00e9valuer ou de remplacer les composants s\u00e9par\u00e9ment. L'int\u00e9gration technique renforce alors les d\u00e9pendances.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C'est pr\u00e9cis\u00e9ment la raison pour laquelle la direction et la supervision doivent apprendre \u00e0 examiner les d\u00e9pendances critiques. Il ne s'agit pas seulement de savoir quel logiciel nous utilisons, mais surtout de savoir sans quelles fonctions num\u00e9riques l'institution ne pourra pas fonctionner demain. Mais surtout : sans quelles fonctions num\u00e9riques l'institution ne pourra-t-elle pas fonctionner demain ?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>L'IA rend la question de la souverainet\u00e9 encore plus sensible<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cette question devient d'autant plus urgente que l'IA s'ajoute aux logiciels existants. Le d\u00e9bat sur l'IA porte souvent sur l'efficacit\u00e9 ou l'innovation, mais pour les institutions culturelles, il touche au moins autant aux droits, \u00e0 la r\u00e9putation et au contr\u00f4le. L'agitation autour d'Adobe en juin 2024 en est l'illustration. Suite aux critiques des cr\u00e9ateurs, Adobe a publiquement clarifi\u00e9 qu'elle n'entra\u00eenait pas l'IA g\u00e9n\u00e9rative sur le contenu de ses clients et que cet engagement serait explicitement ajout\u00e9 \u00e0 ses conditions g\u00e9n\u00e9rales. Le fait qu'une telle clarification ait \u00e9t\u00e9 n\u00e9cessaire en dit long. D\u00e8s lors que l'IA s'imbrique dans les logiciels de cr\u00e9ation, la discussion s'oriente imm\u00e9diatement vers la gouvernance : qu'est-ce qu'un fournisseur est autoris\u00e9 \u00e0 faire avec notre contenu, dans quelles conditions, et pouvons-nous, en tant qu'institution, le justifier ?\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Pour les institutions culturelles, ce probl\u00e8me est encore plus aigu. Apr\u00e8s tout, elles travaillent avec des collections, des images, des textes, des contenus \u00e9ducatifs et d'autres informations ayant une valeur culturelle et juridique. La question des outils d'IA utilis\u00e9s ne peut donc jamais \u00eatre dissoci\u00e9e de la question des droits et des flux de donn\u00e9es concern\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Dans le m\u00eame temps, le march\u00e9 montre que la souverainet\u00e9 n'est pas une question de noir ou de blanc. OpenAI a annonc\u00e9 la r\u00e9sidence des donn\u00e9es en Europe en f\u00e9vrier 2025 pour ChatGPT Enterprise, ChatGPT Edu et l'API, et a \u00e9tendu ces capacit\u00e9s \u00e0 d'autres entreprises clientes en novembre 2025. Cela montre que les fournisseurs non europ\u00e9ens agissent sous la pression des exigences europ\u00e9ennes. C'est important pour la gouvernance et la supervision, car sinon le d\u00e9bat devient trop rapidement id\u00e9ologique. Toutes les solutions non europ\u00e9ennes ne sont pas par d\u00e9finition inutilisables, de m\u00eame que toutes les alternatives europ\u00e9ennes n'offrent pas automatiquement une \u00e9chelle, une fonctionnalit\u00e9 ou une s\u00e9curit\u00e9 suffisantes. La question reste donc pos\u00e9e : quelles sont les garanties r\u00e9elles ?\u00a0\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00a0<strong>La souverainet\u00e9 n'est pas un geste, mais une op\u00e9ration de changement<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cela nous am\u00e8ne au point qui est peut-\u00eatre le plus souvent sous-estim\u00e9 dans le d\u00e9bat : le changement n'est pas une d\u00e9claration morale, mais une op\u00e9ration de changement. Les donn\u00e9es doivent \u00eatre migr\u00e9es, les liens reconstruits, les processus modifi\u00e9s et les employ\u00e9s form\u00e9s. Cela demande de l'argent, du temps et de l'attention de la part de l'administration - exactement les trois choses qui sont souvent rares dans le secteur culturel.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'\u00e9tude de cas classique LiMux \u00e0 Munich montre \u00e0 quel point cette voie est compliqu\u00e9e. La ville a d\u00e9cid\u00e9 de migrer vers le logiciel libre en 2004. Le projet a pris des ann\u00e9es, a n\u00e9cessit\u00e9 un red\u00e9veloppement, une personnalisation et un ajustement organisationnel, avant d'\u00eatre partiellement abandonn\u00e9. La le\u00e7on \u00e0 tirer n'est pas que la souverainet\u00e9 est impossible, mais qu'elle n'a une chance de succ\u00e8s que si la gouvernance et l'organisation prennent au s\u00e9rieux les co\u00fbts de transition, le changement de culture et la persistance politique.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Pour les institutions culturelles, cela signifie que la souverainet\u00e9 logicielle ne doit pas \u00eatre comprise comme une autarcie. Personne n'\u00e9teint la technologie mondiale pour un moment demain. Il s'agit d'autre chose : d'une orientation m\u00fbrement r\u00e9fl\u00e9chie. Savoir o\u00f9 sont les d\u00e9pendances. Comprendre quels syst\u00e8mes sont essentiels \u00e0 la mission. Distinguer les risques juridiques, op\u00e9rationnels ou strat\u00e9giques. Puis \u00e9laborer des politiques adapt\u00e9es aux capacit\u00e9s de l'organisation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C'est moins h\u00e9ro\u00efque qu'une violation num\u00e9rique majeure. Mais c'est de la gouvernance. Et probablement exactement ce dont le secteur a besoin en ce moment. Car la v\u00e9ritable privation de libert\u00e9 ne commence pas lorsqu'une institution est d\u00e9pendante d'un logiciel. Elle commence lorsque la gouvernance et la supervision ne savent plus exactement de quoi il s'agit - et ne peuvent donc pas d\u00e9cider correctement de la marche \u00e0 suivre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Guido van Nispen \u00e9crit : Derri\u00e8re la promesse d'une autonomie num\u00e9rique se cache une r\u00e9alit\u00e9 plus complexe. En y regardant de plus pr\u00e8s, on constate que la souverainet\u00e9 logicielle n'est pas un choix, mais un enjeu de gouvernance. Cet article montre o\u00f9 na\u00eet r\u00e9ellement la d\u00e9pendance \u2014 et pourquoi c'est pr\u00e9cis\u00e9ment l\u00e0 qu'il faut reprendre le contr\u00f4le.<\/p>","protected":false},"author":1273,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","_themeisle_gutenberg_block_has_review":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"federated","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15614,9392,11687],"tags":[15741,16504],"class_list":["post-101076","post","type-post","status-publish","format-standard","hentry","category-beleid","category-internet","category-donatie-gevraagd","tag-artificiele-intelligentie","tag-governance-code"],"featured_image_url":[],"post_author":"Guido van Nispen","assigned_categories":"beleid, INTERNET, WAARDEER &amp; DONEER!","jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":100680,"url":"https:\/\/cultureelpersbureau.nl\/fr\/2026\/02\/de-mythe-van-de-digitale-rijbaan-waarom-de-culturele-sector-niet-even-kan-overstappen-op-soevereine-europese-it\/","url_meta":{"origin":101076,"position":0},"title":"Le mythe de la voie num\u00e9rique : pourquoi le secteur culturel ne peut pas passer \u2018bri\u00e8vement\u2019 \u00e0 une technologie de l'information europ\u00e9enne souveraine","author":"Guido van Nispen","date":"15 f\u00e9vrier 2026","format":false,"excerpt":"La souverainet\u00e9 num\u00e9rique semble attrayante, mais il ne s'agit pas d'une simple conversion. La comparaison avec les Jours H de la Su\u00e8de masque la r\u00e9alit\u00e9 num\u00e9rique complexe dans laquelle op\u00e8rent les institutions culturelles. Sur la d\u00e9pendance, les cyber-risques et la r\u00e9alit\u00e9 de la gouvernance - et pourquoi le r\u00e9alisme est plus urgent que l'ambition. Lire pourquoi.","rel":"","context":"Dans &quot;beleid&quot;","block_context":{"text":"beleid","link":"https:\/\/cultureelpersbureau.nl\/fr\/genre\/beleid\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":100551,"url":"https:\/\/cultureelpersbureau.nl\/fr\/2026\/01\/musea-zijn-soft-targets-waarom-is-cyberveiligheid-nog-altijd-geen-serieuze-bestuurszaak\/","url_meta":{"origin":101076,"position":1},"title":"Les mus\u00e9es sont des cibles faciles - Pourquoi la cybers\u00e9curit\u00e9 n'est-elle toujours pas une question de gouvernance s\u00e9rieuse ?","author":"Guido van Nispen","date":"27 janvier 2026","format":false,"excerpt":"Les mus\u00e9es id\u00e9alisent le vol physique, mais sous-estiment la vuln\u00e9rabilit\u00e9 num\u00e9rique. Cet article explique pourquoi les cyberincidents ne sont pas le fruit du hasard, mais rel\u00e8vent d'une d\u00e9faillance de la direction \u2014 et pourquoi la r\u00e9silience num\u00e9rique est d\u00e9sormais tout aussi fondamentale que la s\u00e9curit\u00e9 des r\u00e9serves ou la protection contre les incendies.","rel":"","context":"Dans &quot;beleid&quot;","block_context":{"text":"beleid","link":"https:\/\/cultureelpersbureau.nl\/fr\/genre\/beleid\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":100113,"url":"https:\/\/cultureelpersbureau.nl\/fr\/2025\/12\/bestuurders-praten-over-ai-makers-voelen-de-gevolgen\/","url_meta":{"origin":101076,"position":2},"title":"Les dirigeants parlent d'IA, les cr\u00e9ateurs en ressentent les cons\u00e9quences","author":"Guido van Nispen","date":"19 d\u00e9cembre 2025","format":false,"excerpt":"Les conducteurs parlent de l'IA comme d'une strat\u00e9gie, les cr\u00e9ateurs la vivent comme une r\u00e9alit\u00e9. Quatre rapports r\u00e9cents montrent que l'IA n'est pas un outil neutre, mais un changement de pouvoir, de risque et de responsabilit\u00e9 au sein de la culture et des m\u00e9dias. Les gains de productivit\u00e9 sont internalis\u00e9s par les organisations, tandis que l'incertitude et la perte de revenus p\u00e8sent principalement sur les freelances et les cr\u00e9ateurs. Les...","rel":"","context":"Dans &quot;beleid&quot;","block_context":{"text":"beleid","link":"https:\/\/cultureelpersbureau.nl\/fr\/genre\/beleid\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":100562,"url":"https:\/\/cultureelpersbureau.nl\/fr\/2026\/01\/digitale-volwassenheid-kan-zich-geen-zesje-meer-veroorloven\/","url_meta":{"origin":101076,"position":3},"title":"La maturit\u00e9 num\u00e9rique ne peut plus se permettre de se contenter de six","author":"Guido van Nispen","date":"29 janvier 2026","format":false,"excerpt":"La maturit\u00e9 num\u00e9rique ne peut plus se contenter d\u2019une note de 6. Le secteur culturel n\u00e9erlandais fait des progr\u00e8s visibles en mati\u00e8re de num\u00e9risation, mais le rythme reste en de\u00e7\u00e0 de la r\u00e9alit\u00e9 d\u2019un monde de plus en plus marqu\u00e9 par l\u2019IA, les donn\u00e9es et les cyberrisques. Une \u00e9tude r\u00e9cente men\u00e9e par DEN montre que de nombreuses institutions restent enlis\u00e9es dans\u2026","rel":"","context":"Dans &quot;beleid&quot;","block_context":{"text":"beleid","link":"https:\/\/cultureelpersbureau.nl\/fr\/genre\/beleid\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/cultureelpersbureau.nl\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-29-at-10.14.03-scaled.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/cultureelpersbureau.nl\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-29-at-10.14.03-scaled.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/cultureelpersbureau.nl\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-29-at-10.14.03-scaled.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/cultureelpersbureau.nl\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-29-at-10.14.03-scaled.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/cultureelpersbureau.nl\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-29-at-10.14.03-scaled.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/cultureelpersbureau.nl\/wp-content\/uploads\/2026\/01\/Screenshot-2026-01-29-at-10.14.03-scaled.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":100862,"url":"https:\/\/cultureelpersbureau.nl\/fr\/2026\/03\/als-zelfs-een-telecombedrijf-het-niet-kan-voorkomen-wat-de-culturele-sector-kan-leren-van-de-odido-hack\/","url_meta":{"origin":101076,"position":4},"title":"Quand m\u00eame une entreprise de t\u00e9l\u00e9communications ne peut pas l'emp\u00eacher : ce que le secteur culturel peut apprendre du piratage d'Odido","author":"Guido van Nispen","date":"7 mars 2026","format":false,"excerpt":"M\u00eame une entreprise de t\u00e9l\u00e9communications forte de centaines de sp\u00e9cialistes en informatique s'est av\u00e9r\u00e9e incapable d'emp\u00eacher une violation de donn\u00e9es. Le piratage d'Odido r\u00e9v\u00e8le la vuln\u00e9rabilit\u00e9 des organisations lorsque l'identit\u00e9 et les donn\u00e9es sont au premier plan. Pour les mus\u00e9es et les institutions culturelles, la le\u00e7on la plus importante ne r\u00e9side pas dans la technologie, mais dans la gouvernance et une gestion consciente des risques.","rel":"","context":"Dans &quot;beleid&quot;","block_context":{"text":"beleid","link":"https:\/\/cultureelpersbureau.nl\/fr\/genre\/beleid\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":100931,"url":"https:\/\/cultureelpersbureau.nl\/fr\/2026\/03\/cyber-hacks-101-van-ethische-hackers-tot-criminele-bendes-wat-bestuurders-en-toezichthouders-in-de-cultuursector-moeten-weten-over-moderne-cyberdreigingen\/","url_meta":{"origin":101076,"position":5},"title":"Cyber-attaques 101 : ce que les directeurs et les r\u00e9gulateurs du secteur culturel doivent savoir","author":"Guido van Nispen","date":"15 mars 2026","format":false,"excerpt":"Guido van Nispen \u00e9crit : \u201cDans un secteur qui prosp\u00e8re gr\u00e2ce \u00e0 la confiance du public, la cyber-r\u00e9silience a depuis longtemps cess\u00e9 d'\u00eatre une hygi\u00e8ne de bureau. Elle fait d\u00e9sormais partie de l'infrastructure culturelle elle-m\u00eame.\u201d...","rel":"","context":"Dans &quot;beleid&quot;","block_context":{"text":"beleid","link":"https:\/\/cultureelpersbureau.nl\/fr\/genre\/beleid\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_shortlink":"https:\/\/wp.me\/p3yKke-qig","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/cultureelpersbureau.nl\/fr\/wp-json\/wp\/v2\/posts\/101076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cultureelpersbureau.nl\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cultureelpersbureau.nl\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cultureelpersbureau.nl\/fr\/wp-json\/wp\/v2\/users\/1273"}],"replies":[{"embeddable":true,"href":"https:\/\/cultureelpersbureau.nl\/fr\/wp-json\/wp\/v2\/comments?post=101076"}],"version-history":[{"count":1,"href":"https:\/\/cultureelpersbureau.nl\/fr\/wp-json\/wp\/v2\/posts\/101076\/revisions"}],"predecessor-version":[{"id":101079,"href":"https:\/\/cultureelpersbureau.nl\/fr\/wp-json\/wp\/v2\/posts\/101076\/revisions\/101079"}],"wp:attachment":[{"href":"https:\/\/cultureelpersbureau.nl\/fr\/wp-json\/wp\/v2\/media?parent=101076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cultureelpersbureau.nl\/fr\/wp-json\/wp\/v2\/categories?post=101076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cultureelpersbureau.nl\/fr\/wp-json\/wp\/v2\/tags?post=101076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}